{"id":12103,"date":"2019-07-29T08:33:04","date_gmt":"2019-07-29T06:33:04","guid":{"rendered":"https:\/\/grupsa.com\/centros-comerciales-y-retail\/"},"modified":"2026-09-01T11:51:35","modified_gmt":"2026-09-01T09:51:35","slug":"centres-commerciaux-et-retail","status":"publish","type":"page","link":"https:\/\/grupsa.com\/fr\/centres-commerciaux-et-retail\/","title":{"rendered":"Centres Commerciaux et Retail"},"content":{"rendered":"<div id=\"pl-12103\"  class=\"panel-layout\" ><div id=\"pg-12103-0\"  class=\"panel-grid panel-has-style\" ><div data-overlay-opactity=\"1\" class=\"panel-row-style panel-row-style-for-12103-0\" ><div id=\"pgc-12103-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-12103-0-0-0\" class=\"so-panel widget widget_themegrill_flash_image tg-widget tg-image-widget panel-first-child\" data-index=\"0\" ><div class=\"tg-image-block\">\r\n\t\t\t<img decoding=\"async\" data-src=\"https:\/\/grupsa.com\/wp-content\/uploads\/2019\/07\/Centros-Comerciales.jpg\" alt=\"Puertas para centros comerciales y retail\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1200px; --smush-placeholder-aspect-ratio: 1200\/552;\" \/>\r\n\t\t<\/div>\r\n<\/div><div id=\"panel-12103-0-0-1\" class=\"so-panel widget widget_themegrill_flash_heading tg-widget section-title-wrapper\" data-index=\"1\" ><div class=\"wow pulse flash_inherit_color panel-widget-style panel-widget-style-for-12103-0-0-1\" data-wow-offset=\"10\" data-wow-iteration=\"1\" >\t<div class=\"heading heading-left divider-without-icon heading-divider\">\r\n\t<h3 class=\"section-title\">Centres Commerciaux et Retail<\/h3>\r\n\t<div class=\"section-description\">Accessoires securit\u00e9s et fonctionnels<\/div>\r\n<\/div>\r\n<\/div><\/div><div id=\"panel-12103-0-0-2\" class=\"so-panel widget widget_text\" data-index=\"2\" >\t\t\t<div class=\"textwidget\"><p>GRUPSA Door Systems propose une large gamme de solutions pour les centres commerciaux et les entr\u00e9es de vente au d\u00e9tail. Nos syst\u00e8mes d&rsquo;acc\u00e8s sont con\u00e7us et fabriqu\u00e9s pour r\u00e9pondre aux besoins des<br \/>\ntout projet architectural: <strong><a href=\"https:\/\/grupsa.com\/fr\/portes-tournantes\/\">Portes Tournantes<\/a><\/strong>, <a href=\"https:\/\/grupsa.com\/fr\/portes-automatiques-vitrees\/\"><strong>Portes Automatiques&#8230;<\/strong><\/a><\/p>\n<p>Notre grande vari\u00e9t\u00e9 de finitions et notre conception personnalis\u00e9e font de nos syst\u00e8mes de portes automatiques la meilleure option sur le march\u00e9, garantissant leur durabilit\u00e9, un entretien r\u00e9duit et<br \/>\nretour sur investissement.<\/p>\n<\/div>\n\t\t<\/div><div id=\"panel-12103-0-0-3\" class=\"so-panel widget widget_themegrill_flash_separator tg-widget separator-wrapper panel-last-child\" data-index=\"3\" ><div class=\"panel-widget-style panel-widget-style-for-12103-0-0-3\" ><div style='margin-top:1px;margin-bottom:7px'  class=\"separator separator-center\">\r\n\t<div class='separator-inner' style='width:100px' ><\/div>\t\t<\/div>\r\n<\/div><\/div><\/div><\/div><\/div><div id=\"pg-12103-1\"  class=\"panel-grid panel-has-style\" ><div data-overlay-opactity=\"1\" class=\"panel-row-style panel-row-style-for-12103-1\" ><div id=\"pgc-12103-1-0\"  class=\"panel-grid-cell\" ><div id=\"panel-12103-1-0-0\" class=\"so-panel widget widget_themegrill_flash_image tg-widget tg-image-widget panel-first-child panel-last-child\" data-index=\"4\" ><div class=\"tg-image-block\">\r\n\t\t\t<img decoding=\"async\" data-src=\"https:\/\/grupsa.com\/wp-content\/uploads\/2020\/03\/Grupsa-Centres-Commerciaux-scaled.jpg\" alt=\"Grupsa Centres Commerciaux\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1811px; --smush-placeholder-aspect-ratio: 1811\/2560;\" \/>\r\n\t\t<\/div>\r\n<\/div><\/div><div id=\"pgc-12103-1-1\"  class=\"panel-grid-cell\" ><div id=\"panel-12103-1-1-0\" class=\"so-panel widget widget_text panel-first-child\" data-index=\"5\" ><div class=\"panel-widget-style panel-widget-style-for-12103-1-1-0\" >\t\t\t<div class=\"textwidget\"><p><strong>LES APPLICATIONS<\/strong><\/p>\n<p>Acc\u00e8s principaux<br \/>\nFa\u00e7ades vitr\u00e9es ou murs-rideaux.<br \/>\nEfficacit\u00e9 \u00e9nerg\u00e9tique<br \/>\nSyst\u00e8mes d&rsquo;ouverture synchronis\u00e9s<br \/>\nAcc\u00e8s secondaires ou d&rsquo;urgence<br \/>\nSyst\u00e8mes en mode antipanique ou ER<\/p>\n<\/div>\n\t\t<\/div><\/div><div id=\"panel-12103-1-1-1\" class=\"so-panel widget widget_sow-button panel-last-child\" data-index=\"6\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-button so-widget-sow-button-atom-c0ef6a430664-12103\"\n\t\t\t\n\t\t><div class=\"ow-button-base ow-button-align-left\"\n>\n\t\t\t<a\n\t\t\t\t\thref=\"https:\/\/tdrv.eu\/sXfMY2\"\n\t\t\t\t\tclass=\"sowb-button ow-icon-placement-right ow-button-hover\" target=\"_blank\" rel=\"noopener noreferrer\" \t>\n\t\t<span>\n\t\t\t<span class=\"sow-icon-icomoon\" data-sow-icon=\"&#xe960;\"\n\t\tstyle=\"color: #ffffff\" \n\t\taria-hidden=\"true\"><\/span>\n\t\t\tBrochure\t\t<\/span>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><div id=\"pg-12103-2\"  class=\"panel-grid panel-has-style\" ><div data-overlay-opactity=\"1\" class=\"panel-row-style panel-row-style-for-12103-2\" ><div id=\"pgc-12103-2-0\"  class=\"panel-grid-cell\" ><div id=\"panel-12103-2-0-0\" class=\"so-panel widget widget_themegrill_flash_image tg-widget tg-image-widget panel-first-child\" data-index=\"7\" ><div class=\"tg-image-block\">\r\n\t\t\t<img decoding=\"async\" data-src=\"https:\/\/grupsa.com\/wp-content\/uploads\/2019\/07\/Concesionario.jpg\" alt=\"Puertas autom\u00e1ticas para centros comerciales y retail Grupsa\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1200px; --smush-placeholder-aspect-ratio: 1200\/552;\" \/>\r\n\t\t<\/div>\r\n<\/div><div id=\"panel-12103-2-0-1\" class=\"so-panel widget widget_text panel-last-child\" data-index=\"8\" >\t\t\t<div class=\"textwidget\"><p><strong>CONCESSIONNAIRE DE VOITURES<\/strong><br \/>\n(MADRID, ESPAGNE)<\/p>\n<\/div>\n\t\t<\/div><\/div><div id=\"pgc-12103-2-1\"  class=\"panel-grid-cell\" ><div id=\"panel-12103-2-1-0\" class=\"so-panel widget widget_themegrill_flash_image tg-widget tg-image-widget panel-first-child\" data-index=\"9\" ><div class=\"tg-image-block\">\r\n\t\t\t<img decoding=\"async\" data-src=\"https:\/\/grupsa.com\/wp-content\/uploads\/2019\/07\/Peru-Centro-Comercial.jpg\" alt=\"Peru Centro Comercial \u00b7 Grupsa\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1200px; --smush-placeholder-aspect-ratio: 1200\/552;\" \/>\r\n\t\t<\/div>\r\n<\/div><div id=\"panel-12103-2-1-1\" class=\"so-panel widget widget_text panel-last-child\" data-index=\"10\" >\t\t\t<div class=\"textwidget\"><p><strong>CENTRE COMMERCIAL MEGA PLAZA<\/strong><br \/>\n(LIMA, P\u00c9ROU)<\/p>\n<\/div>\n\t\t<\/div><\/div><\/div><\/div><div id=\"pg-12103-3\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-12103-3-0\"  class=\"panel-grid-cell\" ><div id=\"panel-12103-3-0-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"11\" ><div class=\"panel-widget-style panel-widget-style-for-12103-3-0-0\" >\t\t\t<div class=\"textwidget\"><\/div>\n\t\t<\/div><\/div><\/div><\/div><div id=\"pg-12103-4\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-12103-4-0\"  class=\"panel-grid-cell\" ><div id=\"panel-12103-4-0-0\" class=\"so-panel widget widget_text panel-first-child\" data-index=\"12\" ><div class=\"panel-widget-style panel-widget-style-for-12103-4-0-0\" ><h3 class=\"widget-title\">PROJETS DE R\u00c9F\u00c9RENCE<\/h3>\t\t\t<div class=\"textwidget\"><\/div>\n\t\t<\/div><\/div><div id=\"panel-12103-4-0-1\" class=\"so-panel widget widget_themegrill_flash_separator tg-widget separator-wrapper panel-last-child\" data-index=\"13\" ><div class=\"panel-widget-style panel-widget-style-for-12103-4-0-1\" ><div style='margin-top:1px;margin-bottom:1px'  class=\"separator separator-left\">\r\n\t<div class='separator-inner' style='width:35px' ><\/div>\t\t<\/div>\r\n<\/div><\/div><\/div><\/div><div id=\"pg-12103-5\"  class=\"panel-grid panel-has-style\" ><div data-overlay-opactity=\"1\" class=\"panel-row-style panel-row-style-for-12103-5\" ><div id=\"pgc-12103-5-0\"  class=\"panel-grid-cell\" ><div id=\"panel-12103-5-0-0\" class=\"so-panel widget widget_themegrill_flash_image tg-widget tg-image-widget panel-first-child\" data-index=\"14\" ><div class=\"tg-image-block\">\r\n\t\t\t<img decoding=\"async\" data-src=\"https:\/\/grupsa.com\/wp-content\/uploads\/2019\/07\/avrora-shopping-center.jpg\" alt=\"Avrora Shopping Center \u00b7 Grupsa\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/>\r\n\t\t<\/div>\r\n<\/div><div id=\"panel-12103-5-0-1\" class=\"so-panel widget widget_text\" data-index=\"15\" ><div class=\"panel-widget-style panel-widget-style-for-12103-5-0-1\" >\t\t\t<div class=\"textwidget\"><p><b>CENTRE COMMERCIAL AVRORA<\/b><br \/>\nZAPORIYIA (UKRAINE)<\/p>\n<\/div>\n\t\t<\/div><\/div><div id=\"panel-12103-5-0-2\" class=\"so-panel widget widget_sow-button panel-last-child\" data-index=\"16\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-button so-widget-sow-button-atom-8c35d31a3108-12103\"\n\t\t\t\n\t\t><div class=\"ow-button-base ow-button-align-center\"\n>\n\t\t\t<a\n\t\t\t\t\thref=\"https:\/\/tdrv.eu\/mvHfix\"\n\t\t\t\t\tclass=\"sowb-button ow-icon-placement-right ow-button-hover\" target=\"_blank\" rel=\"noopener noreferrer\" \t>\n\t\t<span>\n\t\t\t\n\t\t\tVoir le projet\t\t<\/span>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><\/div><\/div><div id=\"pgc-12103-5-1\"  class=\"panel-grid-cell panel-grid-cell-empty\" ><\/div><div id=\"pgc-12103-5-2\"  class=\"panel-grid-cell panel-grid-cell-empty panel-grid-cell-mobile-last\" ><\/div><div id=\"pgc-12103-5-3\"  class=\"panel-grid-cell panel-grid-cell-empty\" ><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>GRUPSA Door Systems propose une large gamme de solutions pour les centres commerciaux et les [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-12103","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Portes pour centres commerciaux et magasins - Grupsa<\/title>\n<meta name=\"description\" content=\"Nous fabriquons des portes coulissantes pour locaux commerciaux. Grupsa propose une large gamme de solutions pour l&#039;entr\u00e9e des centres commerciaux.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/grupsa.com\/fr\/centres-commerciaux-et-retail\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Portes pour centres commerciaux et magasins - Grupsa\" \/>\n<meta property=\"og:description\" content=\"Nous fabriquons des portes coulissantes pour locaux commerciaux. Grupsa propose une large gamme de solutions pour l&#039;entr\u00e9e des centres commerciaux.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/grupsa.com\/fr\/centres-commerciaux-et-retail\/\" \/>\n<meta property=\"og:site_name\" content=\"Grupsa\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T09:51:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/grupsa.com\/wp-content\/uploads\/2023\/11\/cropped-1.-Logo-Grupsa-Door-Systems_20221116-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2559\" \/>\n\t<meta property=\"og:image:height\" content=\"1279\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/grupsa.com\\\/fr\\\/centres-commerciaux-et-retail\\\/\",\"url\":\"https:\\\/\\\/grupsa.com\\\/fr\\\/centres-commerciaux-et-retail\\\/\",\"name\":\"Portes pour centres commerciaux et magasins - Grupsa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/grupsa.com\\\/fr\\\/#website\"},\"datePublished\":\"2019-07-29T06:33:04+00:00\",\"dateModified\":\"2026-09-01T09:51:35+00:00\",\"description\":\"Nous fabriquons des portes coulissantes pour locaux commerciaux. Grupsa propose une large gamme de solutions pour l'entr\u00e9e des centres commerciaux.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/grupsa.com\\\/fr\\\/centres-commerciaux-et-retail\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/grupsa.com\\\/fr\\\/centres-commerciaux-et-retail\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/grupsa.com\\\/fr\\\/centres-commerciaux-et-retail\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/grupsa.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Centres Commerciaux et Retail\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/grupsa.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/grupsa.com\\\/fr\\\/\",\"name\":\"Grupsa\",\"description\":\"Accesos que conectan personas\",\"publisher\":{\"@id\":\"https:\\\/\\\/grupsa.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/grupsa.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/grupsa.com\\\/fr\\\/#organization\",\"name\":\"Grupsa\",\"url\":\"https:\\\/\\\/grupsa.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/grupsa.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/grupsa.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/Logo-Grupsa-scaled.png\",\"contentUrl\":\"https:\\\/\\\/grupsa.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/Logo-Grupsa-scaled.png\",\"width\":2560,\"height\":1279,\"caption\":\"Grupsa\"},\"image\":{\"@id\":\"https:\\\/\\\/grupsa.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Portes pour centres commerciaux et magasins - Grupsa","description":"Nous fabriquons des portes coulissantes pour locaux commerciaux. Grupsa propose une large gamme de solutions pour l'entr\u00e9e des centres commerciaux.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/grupsa.com\/fr\/centres-commerciaux-et-retail\/","og_locale":"fr_FR","og_type":"article","og_title":"Portes pour centres commerciaux et magasins - Grupsa","og_description":"Nous fabriquons des portes coulissantes pour locaux commerciaux. Grupsa propose une large gamme de solutions pour l'entr\u00e9e des centres commerciaux.","og_url":"https:\/\/grupsa.com\/fr\/centres-commerciaux-et-retail\/","og_site_name":"Grupsa","article_modified_time":"2026-09-01T09:51:35+00:00","og_image":[{"width":2559,"height":1279,"url":"https:\/\/grupsa.com\/wp-content\/uploads\/2023\/11\/cropped-1.-Logo-Grupsa-Door-Systems_20221116-scaled-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/grupsa.com\/fr\/centres-commerciaux-et-retail\/","url":"https:\/\/grupsa.com\/fr\/centres-commerciaux-et-retail\/","name":"Portes pour centres commerciaux et magasins - Grupsa","isPartOf":{"@id":"https:\/\/grupsa.com\/fr\/#website"},"datePublished":"2019-07-29T06:33:04+00:00","dateModified":"2026-09-01T09:51:35+00:00","description":"Nous fabriquons des portes coulissantes pour locaux commerciaux. Grupsa propose une large gamme de solutions pour l'entr\u00e9e des centres commerciaux.","breadcrumb":{"@id":"https:\/\/grupsa.com\/fr\/centres-commerciaux-et-retail\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/grupsa.com\/fr\/centres-commerciaux-et-retail\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/grupsa.com\/fr\/centres-commerciaux-et-retail\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/grupsa.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Centres Commerciaux et Retail"}]},{"@type":"WebSite","@id":"https:\/\/grupsa.com\/fr\/#website","url":"https:\/\/grupsa.com\/fr\/","name":"Grupsa","description":"Accesos que conectan personas","publisher":{"@id":"https:\/\/grupsa.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/grupsa.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/grupsa.com\/fr\/#organization","name":"Grupsa","url":"https:\/\/grupsa.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/grupsa.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/grupsa.com\/wp-content\/uploads\/2026\/08\/Logo-Grupsa-scaled.png","contentUrl":"https:\/\/grupsa.com\/wp-content\/uploads\/2026\/08\/Logo-Grupsa-scaled.png","width":2560,"height":1279,"caption":"Grupsa"},"image":{"@id":"https:\/\/grupsa.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/grupsa.com\/fr\/wp-json\/wp\/v2\/pages\/12103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/grupsa.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/grupsa.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/grupsa.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/grupsa.com\/fr\/wp-json\/wp\/v2\/comments?post=12103"}],"version-history":[{"count":11,"href":"https:\/\/grupsa.com\/fr\/wp-json\/wp\/v2\/pages\/12103\/revisions"}],"predecessor-version":[{"id":15982,"href":"https:\/\/grupsa.com\/fr\/wp-json\/wp\/v2\/pages\/12103\/revisions\/15982"}],"wp:attachment":[{"href":"https:\/\/grupsa.com\/fr\/wp-json\/wp\/v2\/media?parent=12103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}